{"id":2449,"date":"2026-08-05T10:37:41","date_gmt":"2026-08-05T16:37:41","guid":{"rendered":"https:\/\/www.conradpuntademita.com\/?post_type=experience&#038;p=2449"},"modified":"2026-08-21T11:43:32","modified_gmt":"2026-08-21T17:43:32","slug":"dia-de-muertos","status":"publish","type":"experience","link":"https:\/\/www.conradpuntademita.com\/es\/experiences\/dia-de-muertos\/","title":{"rendered":"dia de muertos"},"content":{"rendered":"<section id=\"banner-block_29f3fd0528e526b5b13d86f44e159eae\" class=\"banner gradient-banner full-height-banner full-height single-room\">\n  <div class=\"banner-wrapper\">\n          <img fetchpriority=\"high\" src=\"https:\/\/cdn.conradpuntademita.com\/wp-content\/uploads\/2026\/08\/05233442\/Dia-de-Muertos-at-Conrad-Punta-de-Mita.jpg\" alt=\"D\u00eda de Muertos en Conrad Punta de Mita\" class=\"banner__img banner__media\" width=\"1500\" height=\"1000\" loading=\"auto\"  decoding=\"async\">\n      <\/div>\n\n      <div class=\"banner-content\">\n              <h1 class=\"banner-title heading1\">D\u00eda de Muertos<\/h1>\n      \n              <h3 class=\"banner-subtitle heading5\">en Conrad Punta de Mita<\/h3>\n              \n      \n<\/section>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<section class=\"block-content\">\n  <div class=\"block-content-wrapper\">\n    <div class=\"block-content__content content\"><p class=\"font-claude-response-body break-words whitespace-normal\" dir=\"ltr\" style=\"text-align: center;\">Ad\u00e9ntrate en el vibrante esp\u00edritu del D\u00eda de Muertos, donde la tradici\u00f3n cobra vida en un tapiz de color y recuerdo. Durante tres d\u00edas, el resort se llena de cempas\u00fachil, copal y la m\u00fasica que define una de las festividades m\u00e1s queridas de M\u00e9xico.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\" dir=\"ltr\" style=\"text-align: center;\">La celebraci\u00f3n comienza con Catrinas y altares luminosos, pintura facial en vivo para invitados de todas las edades y puestos de artesan\u00eda en Colibr\u00ed que exhiben la artesan\u00eda huichol, alebrijes y dulces regionales. Los m\u00e1s peque\u00f1os tienen su propio espacio, desde talleres de disfraces hasta una b\u00fasqueda de dulces por todo el complejo. Cada noche culmina en la playa con una ceremonia en honor a quienes nos precedieron.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\" dir=\"ltr\" style=\"text-align: center;\"><strong>Del 31 de octubre al 2 de noviembre de 2026<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a class=\"btn btn-primary\" href=\"https:\/\/www.hilton.com\/en\/book\/reservation\/deeplink\/?&amp;ctyhocn=PVRPMCI&amp;spec_plan=PGAIRO&amp;requestedRatesOnly=true&amp;arrivalDate=2026-11-01&amp;departureDate=2026-11-04&amp;flexibleDates=true\" target=\"_blank\" rel=\"noopener\">Consulta disponibilidad<\/a>\u00a0 |\u00a0 <a href=\"https:\/\/www.flipsnack.com\/66B9AD5EFB5\/folleto-dia-de-muertos-2026\" target=\"_blank\" rel=\"noopener\">Ver folleto de 2026<\/a><\/p>\n<\/div>\n  <\/div>\n<\/section>\n\n\n\t<section class=\"media-content body-wrapper not-link\" id=\"banner-block_c548f9358465715ce8f6cffa514f794b\">\n\t<div class=\"media-content__left\">\n\t\t\t\t<h2 class=\"heading2 a-up\">\n\t\t\tUn juego de mesa <br\/>de memoria\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t<h4 class=\"media-content__subheading a-up a-delay-1\">Los platos t\u00edpicos de los hogares mexicanos<\/h4>\n\t\t\n\t\t\n\t\t\n\t\t\t\t<div class=\"media-content__text a-up a-delay-2\"><p>Through the first week of November, \u00c1rbol opens each morning with the food that anchors this holiday. Moles, tamales, barbacoa, pipian, pozole, and arroz con leche, prepared by Chef Elba and the \u00c1rbol culinary team. At Colibri, traditional Pan de Muerto is baked fresh with notes of orange, cinnamon, and vanilla, shaped in bone and marigold.\r\n\r\nOn the final night, \u00c1rbol and Tuki close the celebration with cocktails, music, and an evening built around the culture the holiday belongs to.<\/p><\/div>\n\t\t\n\t\t\t\t\t<style>\n\t\t\t.media-content__cta-container {\n\t\t\t\tdisplay: flex;\n\t\t\t\tgap: 10px; \/* Espacio entre botones *\/\n\t\t\t}\n\n\t\t\t.media-content__cta {\n\t\t\t\twhite-space: nowrap; \/* Asegura que no se rompan en l\u00edneas *\/\n\t\t\t}\n\t\t\t<\/style>\n\t\t\t<div class=\"media-content__cta-container\">\n\t\t\t\t<a href=\"mailto:PVRPM.FBReservations@conradhotels.com\" target=\"\" class=\"btn a-up a-delay-4 media-content__cta\">Reserva tu asiento<\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\n\t<div class=\"media-content__right hover-images a-up a-delay-2\">\n\t\t<span class=\"media-content__gradient media-content__gradient-left\"><\/span>\n\t\t<span class=\"media-content__gradient media-content__gradient-right\"><\/span>\n\t\t<span class=\"media-content__gradient media-content__gradient-top\"><\/span>\n\t\t<span class=\"media-content__gradient media-content__gradient-bottom\"><\/span>\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1500\" height=\"1000\" src=\"https:\/\/cdn.conradpuntademita.com\/wp-content\/uploads\/2026\/08\/05233147\/Dia-de-Muertos-at-Conrad-Punta-de-Mita_06.jpg\" class=\"hover-image is-hovered\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/cdn.conradpuntademita.com\/wp-content\/uploads\/2026\/08\/05233147\/Dia-de-Muertos-at-Conrad-Punta-de-Mita_06.jpg 1500w, https:\/\/cdn.conradpuntademita.com\/wp-content\/uploads\/2026\/08\/05233147\/Dia-de-Muertos-at-Conrad-Punta-de-Mita_06-300x200.jpg 300w, https:\/\/cdn.conradpuntademita.com\/wp-content\/uploads\/2026\/08\/05233147\/Dia-de-Muertos-at-Conrad-Punta-de-Mita_06-1024x683.jpg 1024w, https:\/\/cdn.conradpuntademita.com\/wp-content\/uploads\/2026\/08\/05233147\/Dia-de-Muertos-at-Conrad-Punta-de-Mita_06-768x512.jpg 768w, https:\/\/cdn.conradpuntademita.com\/wp-content\/uploads\/2026\/08\/05233147\/Dia-de-Muertos-at-Conrad-Punta-de-Mita_06-18x12.jpg 18w, https:\/\/cdn.conradpuntademita.com\/wp-content\/uploads\/2026\/08\/05233147\/Dia-de-Muertos-at-Conrad-Punta-de-Mita_06-600x400.jpg 600w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t<\/div>\n\n\t\t<\/section>\n\n\n\n<section class=\"taste-gallery\" id=\"banner-block_f9a1e8e4d90ceb81d6e30266477eabfc\">\n  <div class=\"taste-gallery__main\">\n          <h2 class=\"heading2 a-up\">Experiencias para descubrir<\/h2>\n    \n    \n          <div class=\"content taste-gallery__content a-up a-delay-2\">Desde el arte hasta la tradici\u00f3n, cada experiencia est\u00e1 dise\u00f1ada para involucrar a los visitantes de todas las edades y sumergirlos en el esp\u00edritu del D\u00eda de Muertos.<\/div>\n    \n      <\/div>\n\n      <div class=\"taste-gallery__items\">\n            <div class=\"taste-gallery__cluster\">\n                <div class=\"taste-gallery__item gallery-item a-up a-delay-0\">\n          <div class=\"gallery-item__media\">\n                          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.conradpuntademita.com\/wp-content\/uploads\/2026\/08\/05191055\/Dia-de-Muertos-at-Conrad-Punta-de-Mita_01.jpg\" class=\"gallery-item__img\" alt=\"D\u00eda de Muertos en Conrad Punta de Mita_01\" width=\"1500\" height=\"1000\">\n                      <\/div>\n\n          <div class=\"gallery-item__content\">\n                          <h3 class=\"gallery-item__title\">La revelaci\u00f3n del altar<\/h3>\n            \n                          <div class=\"content\"><p>El elemento central de la celebraci\u00f3n. En colaboraci\u00f3n con Jos\u00e9 Cuervo, los invitados se re\u00fanen para la inauguraci\u00f3n del altar del resort, con c\u00f3cteles, canap\u00e9s y un primer vistazo a una tradici\u00f3n con siglos de historia.<\/p><\/div>\n            \n                      <\/div>\n        <\/div>\n                <div class=\"taste-gallery__item gallery-item a-up a-delay-1\">\n          <div class=\"gallery-item__media\">\n                          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.conradpuntademita.com\/wp-content\/uploads\/2026\/08\/05191607\/Dia-de-Muertos-at-Conrad-Punta-de-Mita_02.jpg\" class=\"gallery-item__img\" alt=\"D\u00eda de Muertos en Conrad Punta de Mita_02\" width=\"1500\" height=\"1000\">\n                      <\/div>\n\n          <div class=\"gallery-item__content\">\n                          <h3 class=\"gallery-item__title\">Arte Huichol y Alebrijes<\/h3>\n            \n                          <div class=\"content\"><p>En Colibr\u00ed, los artesanos locales comparten su oficio, con intrincados trabajos de abalorios, coloridos alebrijes y dulces artesanales que ofrecen una visi\u00f3n de las tradiciones de la regi\u00f3n.<\/p><\/div>\n            \n                      <\/div>\n        <\/div>\n                <div class=\"taste-gallery__item gallery-item a-up a-delay-2\">\n          <div class=\"gallery-item__media\">\n                          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.conradpuntademita.com\/wp-content\/uploads\/2026\/08\/05193109\/Dia-de-Muertos-at-Conrad-Punta-de-Mita_03.jpg\" class=\"gallery-item__img\" alt=\"D\u00eda de Muertos en Conrad Punta de Mita_03\" width=\"1500\" height=\"1000\">\n                      <\/div>\n\n          <div class=\"gallery-item__content\">\n                          <h3 class=\"gallery-item__title\">Pintura facial<\/h3>\n            \n                          <div class=\"content\"><p>Ni\u00f1os y adultos est\u00e1n invitados a transformarse en Catrinas y Catrines, los personajes emblem\u00e1ticos de la festividad.<\/p><\/div>\n            \n                      <\/div>\n        <\/div>\n              <\/div>\n            <div class=\"taste-gallery__cluster\">\n                <div class=\"taste-gallery__item gallery-item a-up a-delay-3\">\n          <div class=\"gallery-item__media\">\n                          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.conradpuntademita.com\/wp-content\/uploads\/2026\/07\/15173554\/CPM-Dia-de-Muertos-2025.jpg\" class=\"gallery-item__img\" alt=\"Mesa del D\u00eda de Muertos \u2014 Conrad Punta de Mita\" width=\"1500\" height=\"1000\">\n                      <\/div>\n\n          <div class=\"gallery-item__content\">\n                          <h3 class=\"gallery-item__title\">Tradiciones familiares<\/h3>\n            \n                          <div class=\"content\"><p>Talleres de disfraces, una b\u00fasqueda de dulces por todo el complejo y cine al aire libre bajo las estrellas, con una programaci\u00f3n pensada para los hu\u00e9spedes m\u00e1s j\u00f3venes durante los tres d\u00edas.<\/p><\/div>\n            \n                      <\/div>\n        <\/div>\n                <div class=\"taste-gallery__item gallery-item a-up a-delay-4\">\n          <div class=\"gallery-item__media\">\n                          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.conradpuntademita.com\/wp-content\/uploads\/2026\/08\/05193420\/Dia-de-Muertos-at-Conrad-Punta-de-Mita_04.jpg\" class=\"gallery-item__img\" alt=\"D\u00eda de Muertos en Conrad Punta de Mita_04\" width=\"1500\" height=\"1000\">\n                      <\/div>\n\n          <div class=\"gallery-item__content\">\n                          <h3 class=\"gallery-item__title\">La procesi\u00f3n de Catrina<\/h3>\n            \n                          <div class=\"content\"><p>Un desfile simb\u00f3lico por el vest\u00edbulo, donde cada departamento del complejo presenta su propia interpretaci\u00f3n de la Catrina.<\/p><\/div>\n            \n                      <\/div>\n        <\/div>\n                <div class=\"taste-gallery__item gallery-item a-up a-delay-5\">\n          <div class=\"gallery-item__media\">\n                          <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.conradpuntademita.com\/wp-content\/uploads\/2026\/08\/05195343\/Dia-de-Muertos-at-Conrad-Punta-de-Mita_05.jpg\" class=\"gallery-item__img\" alt=\"D\u00eda de Muertos en Conrad Punta de Mita_05\" width=\"1500\" height=\"1000\">\n                      <\/div>\n\n          <div class=\"gallery-item__content\">\n                          <h3 class=\"gallery-item__title\">Ceremonia del atardecer<\/h3>\n            \n                          <div class=\"content\"><p>Cada tarde, la playa concluye con una ceremonia de gratitud y recuerdo, mientras la luz se desvanece y el d\u00eda se devuelve.<\/p><\/div>\n            \n                      <\/div>\n        <\/div>\n              <\/div>\n          <\/div>\n  <\/section>\n\n\n\n<section id=\"offers-module-block_81693a387a35e33a191520dc5f54622e\" class=\"offers-module\">\n  <div class=\"offers-module__info\">\n\n\n\n          <h2 class=\"offers-module__heading heading2 a-up\">Planifica tu visita<\/h2>\n    \n          <h6 class=\"offers-module__subheading heading3 a-up a-delay-1\">Ofertas Especiales<\/h6>\n    \n          <p class=\"offers-module__desc content a-up a-delay-2\">\n        Comience su viaje de relajaci\u00f3n y disfrute de los encantos naturales de este santuario. A solo unos pasos de una de las mejores playas de la Riviera Nayarit, Conrad Punta de Mita est\u00e1 rodeado de serenos paisajes con infinitas opciones para relajarse y divertirse.      <\/p>\n    \n        <div class=\"offers-module__btn--wrapper a-up\">\n      <a href=\"\/es\/ofertas\/\" class=\"btn offers-module__btn\" target=\"\">\n        DESCUBRE M\u00c1S      <\/a>\n    <\/div>\n    \n  <\/div>\n      <div class=\"offers-module__grid swiper\">\n      <div class=\"swiper-wrapper offers-module__swiper\">\n          <article class=\"loop-offer swiper-slide\" data-id=\"17842\">\n    <a href=\"https:\/\/www.hilton.com\/en\/book\/reservation\/deeplink\/?&#038;ctyhocn=PVRPMCI&#038;spec_plan=PGAIRO&#038;requestedRatesOnly=true&#038;arrivalDate=2026-01-01&#038;departureDate=2026-01-04&#038;flexibleDates=true\" target=\"\" rel=\"noopener\">\n      <div class=\"loop-offer__image\">\n                  <div class=\"img-a\">\n            <div class=\"gradient-overlay foto-hover\">\n              <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/cdn.conradpuntademita.com\/wp-content\/uploads\/2025\/12\/15223123\/CPM-Resort-Credit-Offer-585x730.webp\" srcset=\"https:\/\/cdn.conradpuntademita.com\/wp-content\/uploads\/2025\/12\/15223123\/CPM-Resort-Credit-Offer-1170x1000.webp\" alt=\"Mujer relaj\u00e1ndose en la piscina de la azotea con desayuno flotante, champ\u00e1n y vistas panor\u00e1micas al oc\u00e9ano.\" class=\"loop-offer__bg\">\n            <\/div>\n          <\/div>\n        \n      <\/div>\n    <\/a>\n\n    <div class=\"loop-offer__content content\">\n      <h6 class=\"loop-offer__title a-up\">\n        Oferta de cr\u00e9dito del resort      <\/h6>\n              <p class=\"loop-offer__excerpt a-up a-delay-1\">Disfrute de m\u00e1s tiempo para consentirse con hasta 30% de descuento, adem\u00e1s de un cr\u00e9dito de $200 USD para experiencias gastron\u00f3micas y de spa en Conrad Punta de Mita.<\/p>\n      \n\n\n              <a href=\"https:\/\/www.hilton.com\/en\/book\/reservation\/deeplink\/?&#038;ctyhocn=PVRPMCI&#038;spec_plan=PGAIRO&#038;requestedRatesOnly=true&#038;arrivalDate=2026-01-01&#038;departureDate=2026-01-04&#038;flexibleDates=true\" class=\"btn loop-offer__btn  btn-outline\" target=\"\" rel=\"noopener\">\n                        Reservar        <\/a>\n            \n    <\/div>\n  <\/article>\n  <article class=\"loop-offer swiper-slide\" data-id=\"4742\">\n    <a href=\"https:\/\/www.hilton.com\/en\/book\/reservation\/deeplink\/?&#038;ctyhocn=PVRPMCI&#038;spec_plan=OW&#038;requestedRatesOnly=true&#038;arrivalDate=2026-06-01&#038;departureDate=2026-06-04&#038;flexibleDates=true&#038;displayCurrency=MXN\" target=\"_blank\" rel=\"noopener\">\n      <div class=\"loop-offer__image\">\n                  <div class=\"img-a\">\n            <div class=\"gradient-overlay foto-hover\">\n              <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/cdn.conradpuntademita.com\/wp-content\/uploads\/2022\/05\/13123545\/ConradPuntaMita-Spherical-JoeThomas-022022-130-585x730.webp\" srcset=\"https:\/\/cdn.conradpuntademita.com\/wp-content\/uploads\/2022\/05\/13123545\/ConradPuntaMita-Spherical-JoeThomas-022022-130-1170x1365.webp\" alt=\"Algunos \u00e1rboles en la playa con vista al mar en Conrad Punta de Mita.\" class=\"loop-offer__bg\">\n            <\/div>\n          <\/div>\n        \n      <\/div>\n    <\/a>\n\n    <div class=\"loop-offer__content content\">\n      <h6 class=\"loop-offer__title a-up\">\n        Tarifa Residentes Mexicanos      <\/h6>\n              <p class=\"loop-offer__excerpt a-up a-delay-1\">Los residentes mexicanos disfrutan de hasta 50% de descuento, un cr\u00e9dito de 150 USD para el resort por estad\u00eda, desayuno diario, salida tard\u00eda y m\u00e1s en Conrad Punta de Mita. Estancia m\u00ednima de 3 noches. Se requiere identificaci\u00f3n al registrarse.<\/p>\n      \n\n\n              <a href=\"https:\/\/www.hilton.com\/en\/book\/reservation\/deeplink\/?&#038;ctyhocn=PVRPMCI&#038;spec_plan=OW&#038;requestedRatesOnly=true&#038;arrivalDate=2026-06-01&#038;departureDate=2026-06-04&#038;flexibleDates=true&#038;displayCurrency=MXN\" class=\"btn loop-offer__btn  btn-outline\" target=\"_blank\" rel=\"noopener\">\n                        Reservar        <\/a>\n            \n    <\/div>\n  <\/article>\n  <article class=\"loop-offer swiper-slide\" data-id=\"7489\">\n    <a href=\"https:\/\/www.hilton.com\/en\/book\/reservation\/deeplink?&#038;ctyhocn=PVRPMCI&#038;spec_plan=RPSPRO&#038;requestedRatesOnly=true&#038;arrivalDate=2025-02-25&#038;departureDate=2025-03-01&#038;flexibleDates=true\" target=\"\" rel=\"noopener\">\n      <div class=\"loop-offer__image\">\n                  <div class=\"img-a\">\n            <div class=\"gradient-overlay foto-hover\">\n              <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/cdn.conradpuntademita.com\/wp-content\/uploads\/2024\/01\/10160525\/conrad-punta-de-mita-aereal-585x730.webp\" srcset=\"https:\/\/cdn.conradpuntademita.com\/wp-content\/uploads\/2024\/01\/10160525\/conrad-punta-de-mita-aereal-1170x1332.webp\" alt=\"Resort de lujo frente al mar con edificios blancos, piscina sinuosa, palmeras y monta\u00f1as iluminadas por el atardecer en el fondo.\" class=\"loop-offer__bg\">\n            <\/div>\n          <\/div>\n        \n      <\/div>\n    <\/a>\n\n    <div class=\"loop-offer__content content\">\n      <h6 class=\"loop-offer__title a-up\">\n        Cuarta noche por nuestra cuenta      <\/h6>\n              <p class=\"loop-offer__excerpt a-up a-delay-1\">Esc\u00e1pese a la serena belleza de Conrad Punta de Mita y experimente el lujo como nunca antes. Reserve una estad\u00eda de 3 noches y disfrute de la cuarta noche por nuestra cuenta, adem\u00e1s de un cr\u00e9dito de resort de $250.<\/p>\n      \n\n\n              <a href=\"https:\/\/www.hilton.com\/en\/book\/reservation\/deeplink?&#038;ctyhocn=PVRPMCI&#038;spec_plan=RPSPRO&#038;requestedRatesOnly=true&#038;arrivalDate=2025-02-25&#038;departureDate=2025-03-01&#038;flexibleDates=true\" class=\"btn loop-offer__btn  btn-outline\" target=\"\" rel=\"noopener\">\n                        Reservar        <\/a>\n            \n    <\/div>\n  <\/article>\n      <\/div>\n    <\/div>\n  \n      <div class=\"offers-module__extra-link a-up a-delay-3\">\n      <a href=\"https:\/\/www.conradpuntademita.com\/es\/ofertas\/\" target=\"\">DETALLES DE LAS OFERTAS<\/a>\n    <\/div>\n  \n\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Sum\u00e9rgete en una de las festividades m\u00e1s queridas de M\u00e9xico, el D\u00eda de Muertos (1 y 2 de noviembre), donde honramos a nuestros ancestros con coloridos disfraces, decoraciones festivas y recetas centenarias. Acomp\u00e1\u00f1anos en nuestra presentaci\u00f3n, que incluye pintura facial, catrinas, altares, artesan\u00eda y una cena festiva a orillas del Pac\u00edfico.<\/p>","protected":false},"featured_media":20227,"parent":0,"menu_order":22,"template":"","meta":{"_acf_changed":true,"inline_featured_image":false},"experience_category":[56],"experience_season":[34],"class_list":["post-2449","experience","type-experience","status-publish","has-post-thumbnail","hentry","experience_category-holidays","experience_season-fall"],"acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.conradpuntademita.com\/es\/wp-json\/wp\/v2\/experience\/2449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.conradpuntademita.com\/es\/wp-json\/wp\/v2\/experience"}],"about":[{"href":"https:\/\/www.conradpuntademita.com\/es\/wp-json\/wp\/v2\/types\/experience"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conradpuntademita.com\/es\/wp-json\/wp\/v2\/media\/20227"}],"wp:attachment":[{"href":"https:\/\/www.conradpuntademita.com\/es\/wp-json\/wp\/v2\/media?parent=2449"}],"wp:term":[{"taxonomy":"experience_category","embeddable":true,"href":"https:\/\/www.conradpuntademita.com\/es\/wp-json\/wp\/v2\/experience_category?post=2449"},{"taxonomy":"experience_season","embeddable":true,"href":"https:\/\/www.conradpuntademita.com\/es\/wp-json\/wp\/v2\/experience_season?post=2449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}